{"id":1,"date":"2021-04-04T16:31:43","date_gmt":"2021-04-04T16:31:43","guid":{"rendered":"https:\/\/tausend.net\/?p=1"},"modified":"2021-04-04T16:41:41","modified_gmt":"2021-04-04T16:41:41","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/tausend.net\/index.php\/2021\/04\/04\/hello-world\/","title":{"rendered":"Tausend.NET(T)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">2000(s) Urlaubs- und sonstige Abenteuer-Seite(n)<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><br>Da die Zeit w\u00e4hrend unseres Urlaubs meist sowieso kaum ausreicht um alles zu sehen, verzichten wir zuk\u00fcnftig auf das Postkarten schreiben und lassen Euch auf diesem Wege an unserer Reise teilhaben (wenn wir regelm\u00e4\u00dfig zum aktualisieren kommen jedenfalls&#8230;).<br><br>(2)Tausend(s) Gr\u00fc\u00dfe!<br><br>Sylvia &amp; Thomas Tausend<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2000(s) Urlaubs- und sonstige Abenteuer-Seite(n) Da die Zeit w\u00e4hrend unseres Urlaubs meist sowieso kaum ausreicht um alles zu sehen, verzichten wir zuk\u00fcnftig auf das Postkarten schreiben und lassen Euch auf diesem Wege an unserer Reise teilhaben (wenn wir regelm\u00e4\u00dfig zum aktualisieren kommen jedenfalls&#8230;). (2)Tausend(s) Gr\u00fc\u00dfe! Sylvia &amp; Thomas Tausend<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":3,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":7,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions\/7"}],"wp:attachment":[{"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tausend.net\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}